{"id":7860,"date":"2025-06-29T19:15:16","date_gmt":"2025-06-29T17:15:16","guid":{"rendered":"https:\/\/smc-news.ch\/?p=7860"},"modified":"2025-06-30T11:37:47","modified_gmt":"2025-06-30T09:37:47","slug":"publication-cle-recommandations-interdisciplinaires-dutilisation-par-le-groupe-de-travail-smc-new-drugs","status":"publish","type":"post","link":"https:\/\/smc-news.ch\/fr\/publication-cle-recommandations-interdisciplinaires-dutilisation-par-le-groupe-de-travail-smc-new-drugs\/","title":{"rendered":"Publication cl\u00e9 \u00ab Recommandations interdisciplinaires d&rsquo;utilisation \u00bb par le groupe de travail SMC \u00ab New Drugs \u00bb"},"content":{"rendered":"\n<p><strong>La SMC publie de nouvelles recommendations sur l&rsquo;utilisation des nouveaux m\u00e9dicaments contre la maladie d&rsquo;Alzheimer en Suisse<\/strong><strong><\/strong><\/p>\n\n<p><strong>\u00abAnti-amyloid monoclonal antibodies for the treatment of Alzheimer disease: Intersocietal recommendations for their appropriate use in Switzerland\u00bb.<\/strong><\/p>\n\n<p>Sous la direction du Dr Ansgar Felbecker et du Prof. Giovanni Frisoni, un groupe d&rsquo;experts suisses en d\u00e9mence a \u00e9labor\u00e9 des recommandations pour une utilisation s\u00fbre des nouveaux anticorps anti-amylo\u00efdes contre la maladie d&rsquo;Alzheimer. Des repr\u00e9sentants de toutes les disciplines concern\u00e9es ainsi que l&rsquo;organisation de patients Alzheimer Suisse y ont particip\u00e9. <\/p>\n\n<p>Ce large consensus doit contribuer \u00e0 rendre possible l&rsquo;utilisation des nouvelles th\u00e9rapies en Suisse de mani\u00e8re s\u00fbre, efficace et rentable. Dans ce contexte, la bonne s\u00e9lection des patients rev\u00eat une grande importance afin d&rsquo;obtenir la meilleure efficacit\u00e9 avec des effets secondaires acceptables.  <\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/karger.com\/pages\/newsroom-media-release-use-of-anti-amyloid-monoclonal-antibodies\">vers la publication<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La SMC publie de nouvelles recommendations sur l&rsquo;utilisation des nouveaux m\u00e9dicaments contre la maladie d&rsquo;Alzheimer en Suisse \u00abAnti-amyloid monoclonal antibodies for the treatment of Alzheimer disease: Intersocietal recommendations for their appropriate use in Switzerland\u00bb. Sous la direction du Dr Ansgar Felbecker et du Prof. Giovanni Frisoni, un groupe d&rsquo;experts suisses en d\u00e9mence a \u00e9labor\u00e9 des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-7860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-smc"],"_links":{"self":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/7860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/comments?post=7860"}],"version-history":[{"count":1,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/7860\/revisions"}],"predecessor-version":[{"id":7861,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/7860\/revisions\/7861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/media\/6757"}],"wp:attachment":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/media?parent=7860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/categories?post=7860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/tags?post=7860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}