{"id":7864,"date":"2025-06-29T19:15:27","date_gmt":"2025-06-29T17:15:27","guid":{"rendered":"https:\/\/smc-news.ch\/?p=7864"},"modified":"2025-06-30T11:38:07","modified_gmt":"2025-06-30T09:38:07","slug":"kick-off-groupe-de-travail-femmes-demence-17-02-2025","status":"publish","type":"post","link":"https:\/\/smc-news.ch\/fr\/kick-off-groupe-de-travail-femmes-demence-17-02-2025\/","title":{"rendered":"Kick-Off groupe de travail \u00ab femmes\/d\u00e9mence \u00bb 17.02.2025"},"content":{"rendered":"\n<p><strong>La Swiss Memory Clinics (SMC) pr\u00e9voit de publier un document de synth\u00e8se sur le th\u00e8me<em> de la sant\u00e9 des femmes et de la d\u00e9mence<\/em>. Un groupe de travail a \u00e9t\u00e9 mis en place sous la direction de Gabriela Latour, membre du comit\u00e9 de la SMC. <\/strong><\/p>\n\n<p>Le contexte est le mandat donn\u00e9 par le Conseil f\u00e9d\u00e9ral aux services f\u00e9d\u00e9raux, dont l&rsquo;OFSP, de prendre davantage en compte les besoins des femmes en mati\u00e8re de sant\u00e9 dans la recherche, la formation, la pr\u00e9vention et les soins. A partir de 2025, ces aspects devront \u00e9galement \u00eatre int\u00e9gr\u00e9s dans le travail de la Plateforme nationale sur la d\u00e9mence. La prise de position met en lumi\u00e8re les diff\u00e9rences sp\u00e9cifiques au genre dans la pr\u00e9vention, le diagnostic et le traitement des pathologies d\u00e9mentielles. Le groupe de travail interdisciplinaire tr\u00e8s engag\u00e9 a d\u00e9j\u00e0 commenc\u00e9 son travail. Des mises \u00e0 jour suivront au fur et \u00e0 mesure.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Swiss Memory Clinics (SMC) pr\u00e9voit de publier un document de synth\u00e8se sur le th\u00e8me de la sant\u00e9 des femmes et de la d\u00e9mence. Un groupe de travail a \u00e9t\u00e9 mis en place sous la direction de Gabriela Latour, membre du comit\u00e9 de la SMC. Le contexte est le mandat donn\u00e9 par le Conseil f\u00e9d\u00e9ral [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-7864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-smc"],"_links":{"self":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/7864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/comments?post=7864"}],"version-history":[{"count":1,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/7864\/revisions"}],"predecessor-version":[{"id":7865,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/7864\/revisions\/7865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/media\/6757"}],"wp:attachment":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/media?parent=7864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/categories?post=7864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/tags?post=7864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}