{"id":8005,"date":"2025-10-28T09:49:51","date_gmt":"2025-10-28T08:49:51","guid":{"rendered":"https:\/\/smc-news.ch\/?p=8005"},"modified":"2025-10-28T09:49:51","modified_gmt":"2025-10-28T08:49:51","slug":"groupe-de-travail-prevention","status":"publish","type":"post","link":"https:\/\/smc-news.ch\/fr\/groupe-de-travail-prevention\/","title":{"rendered":"Groupe de travail \u00ab Pr\u00e9vention \u00bb"},"content":{"rendered":"\n<p><strong>Ind\u00e9pendamment de l&rsquo;autorisation \u00e9ventuelle de nouveaux anticorps anti-amylo\u00efdes, la pr\u00e9vention reste un pilier important du traitement des maladies d\u00e9mentielles.<\/strong><\/p>\n\n<p>Afin de donner encore plus d&rsquo;importance \u00e0 ce sujet, un groupe de travail largement soutenu et dirig\u00e9 par le Prof. Dr Bogdan Draganski \u00e9laborera des recommandations pour la pr\u00e9vention des maladies d\u00e9mentielles, qui seront ensuite mises \u00e0 la disposition des membres de l&rsquo;association Swiss Memory Clinics.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ind\u00e9pendamment de l&rsquo;autorisation \u00e9ventuelle de nouveaux anticorps anti-amylo\u00efdes, la pr\u00e9vention reste un pilier important du traitement des maladies d\u00e9mentielles. Afin de donner encore plus d&rsquo;importance \u00e0 ce sujet, un groupe de travail largement soutenu et dirig\u00e9 par le Prof. Dr Bogdan Draganski \u00e9laborera des recommandations pour la pr\u00e9vention des maladies d\u00e9mentielles, qui seront ensuite mises [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-8005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe-smc"],"_links":{"self":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/8005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/comments?post=8005"}],"version-history":[{"count":1,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/8005\/revisions"}],"predecessor-version":[{"id":8006,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/posts\/8005\/revisions\/8006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/media\/6757"}],"wp:attachment":[{"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/media?parent=8005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/categories?post=8005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smc-news.ch\/fr\/wp-json\/wp\/v2\/tags?post=8005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}