{"id":7993,"date":"2025-10-28T09:48:39","date_gmt":"2025-10-28T08:48:39","guid":{"rendered":"https:\/\/smc-news.ch\/?p=7993"},"modified":"2025-10-28T09:48:39","modified_gmt":"2025-10-28T08:48:39","slug":"evento-del-forum-piattaforma-nazionale-sulla-demenza-07-11-2025","status":"publish","type":"post","link":"https:\/\/smc-news.ch\/it\/evento-del-forum-piattaforma-nazionale-sulla-demenza-07-11-2025\/","title":{"rendered":"Evento del forum Piattaforma nazionale sulla demenza 07.11.2025"},"content":{"rendered":"\n<p>Quest&#8217;anno l&#8217;attenzione sar\u00e0 focalizzata sulla <strong><strong><a href=\"https:\/\/www.bag.admin.ch\/de\/gesundheitliche-vorausplanung-gvp\">pianificazione sanitaria anticipata<\/a><\/strong><\/strong><strong> (PSA), con particolare riferimento alle persone affette da demenza. La PSA offre la possibilit\u00e0 di riflettere sui propri valori e sulle proprie idee in merito al trattamento e all&#8217;assistenza in caso di malattia, incidente o necessit\u00e0 di cure e di metterli per iscritto a favore di terzi, ad esempio in un testamento biologico. <\/strong><\/p>\n\n<p>La mattina saranno presentate le attivit\u00e0 nazionali, seguite da approfondimenti pratici provenienti da case di cura sull&#8217;attuazione efficace della PSA. Il pomeriggio vi aspetter\u00e0 un programma variegato con due turni di sessioni parallele: in ogni turno potrete scegliere una relazione introduttiva che approfondisce un tema della PSA (ad es. nelle persone affette da demenza). <\/p>\n\n<p>La giornata si concluder\u00e0 con una discussione sui temi dell&#8217;autonomia e della dignit\u00e0 nella pratica.<\/p>\n\n<p><\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/smc-news.ch\/wp-content\/uploads\/2025\/09\/NPD_Forumsveranstaltung-07.11.2025-1.pdf\">Ulteriori informazioni e programma dell&#8217;evento del forum (in tedesco)<\/a><\/div>\n<\/div>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/smc-news.ch\/wp-content\/uploads\/2025\/09\/NPD_Forumsveranstaltung-07.11.2025_FR.pdf\">Ulteriori informazioni e programma dell&#8217;evento del forum (in francese)<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quest&#8217;anno l&#8217;attenzione sar\u00e0 focalizzata sulla pianificazione sanitaria anticipata (PSA), con particolare riferimento alle persone affette da demenza. La PSA offre la possibilit\u00e0 di riflettere sui propri valori e sulle proprie idee in merito al trattamento e all&#8217;assistenza in caso di malattia, incidente o necessit\u00e0 di cure e di metterli per iscritto a favore di terzi, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-7993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"_links":{"self":[{"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/posts\/7993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/comments?post=7993"}],"version-history":[{"count":1,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/posts\/7993\/revisions"}],"predecessor-version":[{"id":7994,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/posts\/7993\/revisions\/7994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/media\/6764"}],"wp:attachment":[{"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/media?parent=7993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/categories?post=7993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smc-news.ch\/it\/wp-json\/wp\/v2\/tags?post=7993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}